{"id":334,"count":0,"description":"","link":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/minmana\/minmana_category\/4nen\/4_sansu\/4sansu_4\/","name":"\u89d2\u306e\u5927\u304d\u3055","slug":"4sansu_4","taxonomy":"minmana_category","parent":171,"meta":[],"_links":{"self":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category"}],"about":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/taxonomies\/minmana_category"}],"up":[{"embeddable":true,"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category\/171"}],"wp:post_type":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana?minmana_category=334"},{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/ppwp-section?minmana_category=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}