{"id":313,"count":0,"description":"","link":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/minmana\/minmana_category\/3nen\/3_sansu\/3sansu_12\/","name":"\u5186\u3068\u7403","slug":"3sansu_12","taxonomy":"minmana_category","parent":164,"meta":[],"_links":{"self":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category"}],"about":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/taxonomies\/minmana_category"}],"up":[{"embeddable":true,"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana_category\/164"}],"wp:post_type":[{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/minmana?minmana_category=313"},{"href":"https:\/\/www.himi.ed.jp\/kyouikusogo\/index.php\/wp-json\/wp\/v2\/ppwp-section?minmana_category=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}